{"id":177,"count":25,"description":"","link":"https:\/\/www.pranafilmes.com.br\/en\/category\/cinema-en\/","name":"Cinema","slug":"cinema-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cinema<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pranafilmes.com.br\/category\/cinema\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinema\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pranafilmes.com.br\/category\/cinema\/\" \/>\n<meta property=\"og:site_name\" content=\"Prana Filmes\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pranafilmes.com.br\/wp-content\/uploads\/2020\/12\/prana_sharing.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.pranafilmes.com.br\/category\/cinema\/\",\"url\":\"https:\/\/www.pranafilmes.com.br\/category\/cinema\/\",\"name\":\"Cinema\",\"isPartOf\":{\"@id\":\"https:\/\/www.pranafilmes.com.br\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.pranafilmes.com.br\/category\/cinema\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pranafilmes.com.br\/category\/cinema\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pranafilmes.com.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cinema\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pranafilmes.com.br\/#website\",\"url\":\"https:\/\/www.pranafilmes.com.br\/\",\"name\":\"Prana Filmes\",\"description\":\"A produtora de Luciana Tomasi e Carlos Gerbase\",\"publisher\":{\"@id\":\"https:\/\/www.pranafilmes.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pranafilmes.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pranafilmes.com.br\/#organization\",\"name\":\"Prana Filmes\",\"url\":\"https:\/\/www.pranafilmes.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.pranafilmes.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pranafilmes.com.br\/wp-content\/uploads\/2020\/11\/prana-logo.svg\",\"contentUrl\":\"https:\/\/www.pranafilmes.com.br\/wp-content\/uploads\/2020\/11\/prana-logo.svg\",\"width\":442,\"height\":633,\"caption\":\"Prana Filmes\"},\"image\":{\"@id\":\"https:\/\/www.pranafilmes.com.br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinema","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pranafilmes.com.br\/category\/cinema\/","og_locale":"en_US","og_type":"article","og_title":"Cinema","og_url":"https:\/\/www.pranafilmes.com.br\/category\/cinema\/","og_site_name":"Prana Filmes","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.pranafilmes.com.br\/wp-content\/uploads\/2020\/12\/prana_sharing.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.pranafilmes.com.br\/category\/cinema\/","url":"https:\/\/www.pranafilmes.com.br\/category\/cinema\/","name":"Cinema","isPartOf":{"@id":"https:\/\/www.pranafilmes.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/www.pranafilmes.com.br\/category\/cinema\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pranafilmes.com.br\/category\/cinema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pranafilmes.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Cinema"}]},{"@type":"WebSite","@id":"https:\/\/www.pranafilmes.com.br\/#website","url":"https:\/\/www.pranafilmes.com.br\/","name":"Prana Filmes","description":"A produtora de Luciana Tomasi e Carlos Gerbase","publisher":{"@id":"https:\/\/www.pranafilmes.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pranafilmes.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.pranafilmes.com.br\/#organization","name":"Prana Filmes","url":"https:\/\/www.pranafilmes.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pranafilmes.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.pranafilmes.com.br\/wp-content\/uploads\/2020\/11\/prana-logo.svg","contentUrl":"https:\/\/www.pranafilmes.com.br\/wp-content\/uploads\/2020\/11\/prana-logo.svg","width":442,"height":633,"caption":"Prana Filmes"},"image":{"@id":"https:\/\/www.pranafilmes.com.br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.pranafilmes.com.br\/en\/wp-json\/wp\/v2\/categories\/177"}],"collection":[{"href":"https:\/\/www.pranafilmes.com.br\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.pranafilmes.com.br\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.pranafilmes.com.br\/en\/wp-json\/wp\/v2\/posts?categories=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}